{"id":605,"date":"2014-09-15T23:59:55","date_gmt":"2014-09-15T23:59:55","guid":{"rendered":"http:\/\/www.energyregulationquarterly.ca\/?p=605"},"modified":"2015-01-13T21:20:36","modified_gmt":"2015-01-13T21:20:36","slug":"editorial-3","status":"publish","type":"post","link":"https:\/\/energyregulationquarterly.ca\/fr\/editorials\/editorial-3","title":{"rendered":"\u00c9ditorial"},"content":{"rendered":"<p><\/p>\n<p>La controverse et la complexit\u00e9 entourant l\u2019environnement juridique et politique actuel de la r\u00e9glementation de l\u2019\u00e9nergie prennent de plus en plus d\u2019importance. Cette situation se refl\u00e8te dans plusieurs commentaires de ce quatri\u00e8me num\u00e9ro\u00a0 de la <i>Publication trimestrielle sur la r<\/i>\u00e9<i>glementation de l\u2019\u00e9nergie<\/i>, particuli\u00e8rement ceux concernant les th\u00e8mes tr\u00e8s r\u00e9pandus des droits autochtones et de l\u2019\u00e9valuation environnementale.<\/p>\n<p>Nigel\u00a0Bankes commente l\u2019approbation du gouvernement f\u00e9d\u00e9ral pour le projet Northern Gateway d\u2019Endbridge. Il signale que le Rapport de la commission d\u2019examen conjoint<a href=\"#one\"><sup>1<\/sup><\/a>, qui recommande l\u2019approbation du projet assujettie \u00e0 209\u00a0conditions, fait l\u2019objet de cinq demandes d\u2019examen judiciaire. En outre, le D\u00e9cret en conseil qui ordonne \u00e0 l\u2019Office national de l\u2019\u00e9nergie (ON\u00c9) d\u2019accorder des certificats d\u2019utilit\u00e9 publique pour le projet est \u00e0 la base de neuf autres demandes en vertu de l\u2019article\u00a055 de la <i>Loi de l\u2019Office national de l\u2019\u00e9nergie<\/i><a href=\"#two\"><sup>2<\/sup><\/a>. Cette derni\u00e8re mettra \u00e0 l\u2019\u00e9preuve les responsabilit\u00e9s du Gouverneur en conseil au moment de prendre une d\u00e9cision sur les recommandations de l\u2019ON\u00c9 pour l\u2019approbation des projets de pipeline f\u00e9d\u00e9raux en vertu de la <i>Loi sur l\u2019ON\u00c9<\/i> telle que modifi\u00e9e en 2012.<\/p>\n<p>Le rapport de Bankes sur les contestations de la d\u00e9cision Northern Gateway doit \u00eatre pris en consid\u00e9ration, de concert avec le commentaire de Terri-Lee Oleniuk, Jennifer Fairfax et Patrick G. Welsh concernant la d\u00e9cision de la Cour f\u00e9d\u00e9rale du Canada de r\u00e9voquer la licence \u00e9mise \u00e0 Ontario Power Generation l\u2019autorisant \u00e0 construire de nouvelles unit\u00e9s de g\u00e9n\u00e9ration d\u2019\u00e9lectricit\u00e9 nucl\u00e9aire \u00e0 la centrale nucl\u00e9aire de Darlington. La Cour a ordonn\u00e9 que l\u2019\u00e9valuation environnementale (EE) en vertu de la <i>Loi canadienne sur l\u2019\u00e9valuation environnementale<\/i> soit renvoy\u00e9e devant la commission appropri\u00e9e pour un examen approfondi, y compris l\u2019examen de certains \u00ab\u00a0\u00e9carts\u00a0\u00bb dans l\u2019analyse entreprise au cours de l\u2019EE.<\/p>\n<p>En plus de ces commentaires sur des projets pr\u00e9cis, Richard King, Sylvain Lussier et Jeremy Barretto ont comment\u00e9 la r\u00e9cente d\u00e9cision de <i>Tsilhqot\u2019in<\/i> de la Cour supr\u00eame du Canada sur le titre ancestral<a href=\"#three\"><sup>3<\/sup><\/a>. Ils ont not\u00e9 que l\u2019on a fait r\u00e9f\u00e9rence \u00e0 cette d\u00e9cision de bien des fa\u00e7ons\u00a0: une d\u00e9cision \u00ab\u00a0historique\u00a0\u00bb, qui \u00ab\u00a0change la donne\u00a0\u00bb ou un \u00ab\u00a0jalon\u00a0\u00bb. Leur conclusion\u00a0: \u00ab\u00a0Une d\u00e9cision historique? Oui. Qui change la donne?\u00a0 Pas n\u00e9cessairement\u00a0\u00bb.<\/p>\n<p>Entre-temps, des contestations des d\u00e9cisions r\u00e9glementaires sur d\u2019autres raisons substantielles et motifs de proc\u00e9dure sont toujours en cours. Gordon Kaiser commente deux appels devant la Cour supr\u00eame du Canada concernant des d\u00e9cisions de la Commission de l\u2019\u00e9nergie de l\u2019Ontario et de l\u2019<i>Alberta Energy and Utilities Board <\/i>touchant la doctrine de prudence. Jim<\/p>\n<p>Smellie examine la d\u00e9cision sur l\u2019ali\u00e9nation des actifs de l\u2019<i>Alberta Utilities Commission<\/i>. Nigel Bankes commente sur ce qu\u2019il croit probablement \u00eatre la premi\u00e8re d\u2019un grand nombre de contestations en mati\u00e8re de proc\u00e9dure dans le litige \u00ab\u00a0tr\u00e8s contest\u00e9\u00a0\u00bb entre l\u2019<i>Alberta Market Surveillance Administrator <\/i>et TransAlta, qui concerne de s\u00e9rieuses accusations de manipulation du march\u00e9.<\/p>\n<p>\u00c0 la lumi\u00e8re des nombreuses contestations et de leur port\u00e9e pr\u00e9sent\u00e9es dans ces commentaires, il faut se demander si, aujourd\u2019hui, une d\u00e9cision r\u00e9glementaire est en mesure d\u2019\u00e9viter un examen judiciaire ou des contestations en mati\u00e8re de proc\u00e9dure. Comme il est not\u00e9, de nombreuses contestations tournent autour de l\u2019\u00e9valuation environnementale et des droits autochtones, auxquels il faut ajouter la question connexe de la participation au processus r\u00e9glementaire. Il s\u2019agit de probl\u00e8mes complexes et leur importance sur une grande partie du processus r\u00e9glementaire n\u2019est pas sur le point de diminuer.<\/p>\n<p>Comme il en a \u00e9t\u00e9 question dans l\u2019\u00e9ditorial du troisi\u00e8me num\u00e9ro de la <i>Publication<\/i>, il y a encore d\u2019autres contestations \u00e0 venir concernant les d\u00e9veloppements technologiques qui \u00e9voluent. L\u2019article d\u2019Hugo Schotman, <i>Les r\u00e9seaux intelligents: une perspective europ\u00e9enne de la r\u00e9glementation<\/i>, pr\u00e9sente un aper\u00e7u de la m\u00e9thode suivie par le Conseil des r\u00e9gulateurs europ\u00e9ens de l\u2019\u00e9nergie pour un tel d\u00e9veloppement.<\/p>\n<p>Dans cet environnement dynamique, on peut \u00eatre tent\u00e9 de penser que l\u2019on fait face \u00e0 un nouveau monde en mati\u00e8re de r\u00e9glementation \u00e9nerg\u00e9tique dans lequel les choses sont vraiment diff\u00e9rentes de ce qu\u2019elles \u00e9taient par le pass\u00e9. Il est clair que la r\u00e9glementation de l\u2019\u00e9nergie a \u00e9t\u00e9 lanc\u00e9e en plein c\u0153ur de l\u2019ar\u00e8ne politique et juridique \u00e0 un niveau sans pr\u00e9c\u00e9dent. Les demandes sur le syst\u00e8me ainsi que les attentes par rapport \u00e0 ce dernier pr\u00e9sentent des d\u00e9fis de plus en plus complexes et un grand nombre de personnes ajouteraient une plus grande incertitude r\u00e9glementaire. \u00c0 de nombreux \u00e9gards, le monde de la r\u00e9glementation de l\u2019\u00e9nergie est diff\u00e9rent dans l\u2019environnement d\u2019aujourd\u2019hui, et certains observateurs mettent en doute le r\u00f4le des r\u00e9gulateurs.<\/p>\n<p>Par rapport \u00e0 ce contexte, on peut trouver un certain r\u00e9confort en lisant l\u2019article \u00e0 la une de Ga\u00e9tan Caron, l\u2019ex-pr\u00e9sident r\u00e9cemment retrait\u00e9 de l\u2019Office national de l\u2019\u00e9nergie, qui raconte ses 35\u00a0ann\u00e9es de carri\u00e8re au sein de l\u2019Office\u00a0: <i>R\u00e9glementation \u00e9nerg\u00e9tique f\u00e9d\u00e9rale au Canada\u00a0: se pr\u00e9parer pour l\u2019avenir\u00a0: que peut-on apprendre du pass\u00e9?<\/i> M.\u00a0Caron s\u2019est joint \u00e0 l\u2019Office \u00e0 titre d\u2019ing\u00e9nieur junior en 1979 et il a gravi les \u00e9chelons pour occuper diff\u00e9rents postes de direction avant d\u2019\u00eatre nomm\u00e9 pr\u00e9sident-directeur g\u00e9n\u00e9ral de l\u2019Office.<\/p>\n<p>M.\u00a0Caron mentionne que la mani\u00e8re dont les Canadiens interagissent avec l\u2019ON\u00c9 est le plus grand changement survenu au cours de sa carri\u00e8re de 35\u00a0ans au sein de l\u2019Office. Toutefois, sa conclusion globale est peut-\u00eatre surprenante (y compris pour lui-m\u00eame) et elle vaut la peine d\u2019\u00eatre r\u00e9p\u00e9t\u00e9e\u00a0:<\/p>\n<p>J\u2019ai commenc\u00e9 la r\u00e9daction de cet article en esp\u00e9rant montrer l\u2019\u00e9volution de la r\u00e9glementation \u00e9nerg\u00e9tique f\u00e9d\u00e9rale comparativement \u00e0 ce qu\u2019elle \u00e9tait il y a 35\u00a0ans. M\u00eame s\u2019il existe quelques diff\u00e9rences, selon moi, l\u2019essence de la r\u00e9glementation, ses avantages pour la soci\u00e9t\u00e9 canadienne, les valeurs qui la soutiennent et les principes qui constituent sa fondation n\u2019ont pas chang\u00e9 en 35\u00a0ans, et ne devraient pas changer dans un avenir proche. Il est donc de bon augure pour l\u2019avenir des d\u00e9terminations de l\u2019int\u00e9r\u00eat public et pour l\u2019int\u00e9r\u00eat public canadien.<\/p>\n<p>Que l\u2019on soit d\u2019accord ou non avec cette conclusion, la communaut\u00e9 de la r\u00e9glementation \u00e9nerg\u00e9tique doit trouver un certain r\u00e9confort dans le fait qu\u2019il y a g\u00e9n\u00e9ralement un avantage durable sous-jacent pour la soci\u00e9t\u00e9 \u00e0 tirer d\u2019une r\u00e9glementation fond\u00e9e sur des principes solides.<\/p>\n<ol class=\"footnote\">\n<li><a name=\"one\"><\/a>Le Rapport de la commission d\u2019examen conjoint a fait l\u2019objet d\u2019un commentaire dans le troisi\u00e8me num\u00e9ro de\u00a0<i> la Publication.<\/i><\/li>\n<li><i><a name=\"two\"><\/a><\/i>LRC\u00a01985, c\u00a0N-7 (telle que modifi\u00e9e) (<i>Loi sur l\u2019ON\u00c9<\/i>). L\u2019ON\u00c9 a depuis \u00e9mis les certificats.<\/li>\n<li><a name=\"three\"><\/a>Nation Tsilhqot\u2019in c Colombie-Britannique, 2014 CSC\u00a044.<\/li>\n<\/ol>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La controverse et la complexit\u00e9 entourant l\u2019environnement juridique et politique actuel de la r\u00e9glementation de l\u2019\u00e9nergie prennent de plus en plus d\u2019importance. Cette situation se refl\u00e8te dans plusieurs commentaires de ce quatri\u00e8me num\u00e9ro\u00a0 de la Publication trimestrielle sur la r\u00e9glementation [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"coauthors":[20,21],"class_list":["post-605","post","type-post","status-publish","format-standard","hentry","category-editorials","volume-volume-2-summer-2014"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Editorial\u00c9ditorial - Publication trimestrielle sur la r\u00e8glementation de l\u2019\u00e9nergie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/energyregulationquarterly.ca\/editorials\/editorial-3\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Editorial\u00c9ditorial - Publication trimestrielle sur la r\u00e8glementation de l\u2019\u00e9nergie\" \/>\n<meta property=\"og:description\" content=\"La controverse et la complexit\u00e9 entourant l\u2019environnement juridique et politique actuel de la r\u00e9glementation de l\u2019\u00e9nergie prennent de plus en plus d\u2019importance. Cette situation se refl\u00e8te dans plusieurs commentaires de ce quatri\u00e8me num\u00e9ro\u00a0 de la Publication trimestrielle sur la r\u00e9glementation [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energyregulationquarterly.ca\/editorials\/editorial-3\" \/>\n<meta property=\"og:site_name\" content=\"Publication trimestrielle sur la r\u00e8glementation de l\u2019\u00e9nergie\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-15T23:59:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-01-13T21:20:36+00:00\" \/>\n<meta name=\"author\" content=\"Rowland J. Harrison, c.r., Gordon E. Kaiser\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Wright\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Rowland J. Harrison, c.r., Gordon E. Kaiser\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/energyregulationquarterly.ca\\\/editorials\\\/editorial-3#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/energyregulationquarterly.ca\\\/editorials\\\/editorial-3\"},\"author\":{\"name\":\"Mike Wright\",\"@id\":\"https:\\\/\\\/energyregulationquarterly.ca\\\/#\\\/schema\\\/person\\\/afca014b6f1ac1ca9a298c6a6cdad662\"},\"headline\":\"\u00c9ditorial\",\"datePublished\":\"2014-09-15T23:59:55+00:00\",\"dateModified\":\"2015-01-13T21:20:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/energyregulationquarterly.ca\\\/editorials\\\/editorial-3\"},\"wordCount\":2102,\"commentCount\":0,\"articleSection\":[\"\u00c9ditorial\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/energyregulationquarterly.ca\\\/editorials\\\/editorial-3#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/energyregulationquarterly.ca\\\/editorials\\\/editorial-3\",\"url\":\"https:\\\/\\\/energyregulationquarterly.ca\\\/editorials\\\/editorial-3\",\"name\":\"Editorial\u00c9ditorial - Publication trimestrielle sur la r\u00e8glementation de l\u2019\u00e9nergie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/energyregulationquarterly.ca\\\/#website\"},\"datePublished\":\"2014-09-15T23:59:55+00:00\",\"dateModified\":\"2015-01-13T21:20:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/energyregulationquarterly.ca\\\/#\\\/schema\\\/person\\\/afca014b6f1ac1ca9a298c6a6cdad662\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/energyregulationquarterly.ca\\\/editorials\\\/editorial-3#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/energyregulationquarterly.ca\\\/editorials\\\/editorial-3\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/energyregulationquarterly.ca\\\/editorials\\\/editorial-3#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/energyregulationquarterly.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Editorial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/energyregulationquarterly.ca\\\/#website\",\"url\":\"https:\\\/\\\/energyregulationquarterly.ca\\\/\",\"name\":\"Publication trimestrielle sur la r\u00e8glementation de l\u2019\u00e9nergie\",\"description\":\"Un forum pour discuter et d\u00e9battre des questions touchant les industries r\u00e8glement\u00e9es du secteur de l\u2019\u00e9nergie.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/energyregulationquarterly.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/energyregulationquarterly.ca\\\/#\\\/schema\\\/person\\\/afca014b6f1ac1ca9a298c6a6cdad662\",\"name\":\"Mike Wright\",\"url\":\"https:\\\/\\\/energyregulationquarterly.ca\\\/fr\\\/author\\\/mike-wright\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Editorial\u00c9ditorial - Publication trimestrielle sur la r\u00e8glementation de l\u2019\u00e9nergie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energyregulationquarterly.ca\/editorials\/editorial-3","og_locale":"fr_FR","og_type":"article","og_title":"Editorial\u00c9ditorial - Publication trimestrielle sur la r\u00e8glementation de l\u2019\u00e9nergie","og_description":"La controverse et la complexit\u00e9 entourant l\u2019environnement juridique et politique actuel de la r\u00e9glementation de l\u2019\u00e9nergie prennent de plus en plus d\u2019importance. Cette situation se refl\u00e8te dans plusieurs commentaires de ce quatri\u00e8me num\u00e9ro\u00a0 de la Publication trimestrielle sur la r\u00e9glementation [&hellip;]","og_url":"https:\/\/energyregulationquarterly.ca\/editorials\/editorial-3","og_site_name":"Publication trimestrielle sur la r\u00e8glementation de l\u2019\u00e9nergie","article_published_time":"2014-09-15T23:59:55+00:00","article_modified_time":"2015-01-13T21:20:36+00:00","author":"Rowland J. Harrison, c.r., Gordon E. Kaiser","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mike Wright","Dur\u00e9e de lecture estim\u00e9e":"11 minutes","Written by":"Rowland J. Harrison, c.r., Gordon E. Kaiser"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/energyregulationquarterly.ca\/editorials\/editorial-3#article","isPartOf":{"@id":"https:\/\/energyregulationquarterly.ca\/editorials\/editorial-3"},"author":{"name":"Mike Wright","@id":"https:\/\/energyregulationquarterly.ca\/#\/schema\/person\/afca014b6f1ac1ca9a298c6a6cdad662"},"headline":"\u00c9ditorial","datePublished":"2014-09-15T23:59:55+00:00","dateModified":"2015-01-13T21:20:36+00:00","mainEntityOfPage":{"@id":"https:\/\/energyregulationquarterly.ca\/editorials\/editorial-3"},"wordCount":2102,"commentCount":0,"articleSection":["\u00c9ditorial"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/energyregulationquarterly.ca\/editorials\/editorial-3#respond"]}]},{"@type":"WebPage","@id":"https:\/\/energyregulationquarterly.ca\/editorials\/editorial-3","url":"https:\/\/energyregulationquarterly.ca\/editorials\/editorial-3","name":"Editorial\u00c9ditorial - Publication trimestrielle sur la r\u00e8glementation de l\u2019\u00e9nergie","isPartOf":{"@id":"https:\/\/energyregulationquarterly.ca\/#website"},"datePublished":"2014-09-15T23:59:55+00:00","dateModified":"2015-01-13T21:20:36+00:00","author":{"@id":"https:\/\/energyregulationquarterly.ca\/#\/schema\/person\/afca014b6f1ac1ca9a298c6a6cdad662"},"breadcrumb":{"@id":"https:\/\/energyregulationquarterly.ca\/editorials\/editorial-3#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energyregulationquarterly.ca\/editorials\/editorial-3"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energyregulationquarterly.ca\/editorials\/editorial-3#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/energyregulationquarterly.ca\/"},{"@type":"ListItem","position":2,"name":"Editorial"}]},{"@type":"WebSite","@id":"https:\/\/energyregulationquarterly.ca\/#website","url":"https:\/\/energyregulationquarterly.ca\/","name":"Publication trimestrielle sur la r\u00e8glementation de l\u2019\u00e9nergie","description":"Un forum pour discuter et d\u00e9battre des questions touchant les industries r\u00e8glement\u00e9es du secteur de l\u2019\u00e9nergie.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energyregulationquarterly.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/energyregulationquarterly.ca\/#\/schema\/person\/afca014b6f1ac1ca9a298c6a6cdad662","name":"Mike Wright","url":"https:\/\/energyregulationquarterly.ca\/fr\/author\/mike-wright"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4ekrL-9L","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/energyregulationquarterly.ca\/fr\/wp-json\/wp\/v2\/posts\/605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energyregulationquarterly.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/energyregulationquarterly.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/energyregulationquarterly.ca\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/energyregulationquarterly.ca\/fr\/wp-json\/wp\/v2\/comments?post=605"}],"version-history":[{"count":6,"href":"https:\/\/energyregulationquarterly.ca\/fr\/wp-json\/wp\/v2\/posts\/605\/revisions"}],"predecessor-version":[{"id":929,"href":"https:\/\/energyregulationquarterly.ca\/fr\/wp-json\/wp\/v2\/posts\/605\/revisions\/929"}],"wp:attachment":[{"href":"https:\/\/energyregulationquarterly.ca\/fr\/wp-json\/wp\/v2\/media?parent=605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/energyregulationquarterly.ca\/fr\/wp-json\/wp\/v2\/categories?post=605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/energyregulationquarterly.ca\/fr\/wp-json\/wp\/v2\/tags?post=605"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/energyregulationquarterly.ca\/fr\/wp-json\/wp\/v2\/coauthors?post=605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}